{"id":11,"date":"2024-12-30T11:31:09","date_gmt":"2024-12-30T10:31:09","guid":{"rendered":"http:\/\/localhost\/eagle\/?page_id=11"},"modified":"2024-12-30T11:37:43","modified_gmt":"2024-12-30T10:37:43","slug":"productos","status":"publish","type":"page","link":"https:\/\/www.eagle-glasses.com\/pt\/productos\/","title":{"rendered":"Produtos"},"content":{"rendered":"<script>\n    let familyActive = 0;\n<\/script>\n<div class=\"daterium\" data-no-translation=\"\" data-no-auto-translation=\"\">\n    <header class=\"page-header\">\n        <div class=\"container-page-header\">\n            <div class=\"title-page-header\">\n                <div class=\"wrap\">\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/header>\n\n    <div class=\"wrap\">\n\n        <div class=\"daterium-brand-box\">\n            <div class=\"daterium-brand-menu\">\n                <div class=\"daterium-brand-menu-container\">\n                    <ul class=\"daterium-brand-menu-list\">\n                                                    <li id=\"bmf1\" class=\"daterium-brand-menu-list-item\"\n                                onclick=\"mostrarFamilia('mf1')\">\n                                <h2 class=\"daterium-brand-menu-list-title\">\n                                    <a alt=\"Gafas de protecci\u00f3n\" data-original-text=\"Gafas de protecci\u00f3n\">\n                                        Gafas de protecci\u00f3n                                    <\/a>\n\n                                <\/h2>\n                            <\/li>\n                                                    <li id=\"bmf2\" class=\"daterium-brand-menu-list-item\"\n                                onclick=\"mostrarFamilia('mf2')\">\n                                <h2 class=\"daterium-brand-menu-list-title\">\n                                    <a alt=\"Gafas de protecci\u00f3n graduadas\" data-original-text=\"Gafas de protecci\u00f3n graduadas\">\n                                        Gafas de protecci\u00f3n graduadas                                    <\/a>\n\n                                <\/h2>\n                            <\/li>\n                                                    <li id=\"bmf3\" class=\"daterium-brand-menu-list-item\"\n                                onclick=\"mostrarFamilia('mf3')\">\n                                <h2 class=\"daterium-brand-menu-list-title\">\n                                    <a alt=\"Gafas de sol\" data-original-text=\"Gafas de sol\">\n                                        Gafas de sol                                    <\/a>\n\n                                <\/h2>\n                            <\/li>\n                                                    <li id=\"bmf4\" class=\"daterium-brand-menu-list-item\"\n                                onclick=\"mostrarFamilia('mf4')\">\n                                <h2 class=\"daterium-brand-menu-list-title\">\n                                    <a alt=\"Accesorios gafas\" data-original-text=\"Accesorios gafas\">\n                                        Accesorios gafas                                    <\/a>\n\n                                <\/h2>\n                            <\/li>\n                                            <\/ul>\n                <\/div>\n                                    <div class=\"daterium-subfamilia-list-container\">\n                        <ul class=\"daterium-subfamilia-list\" id=\"smf1\">\n\n                                                            <li id=\"menu-familia-0\" class=\"daterium-brand-menu-subitem\">\n\n                                    <a href=\"#mf1sf0\"\n                                        alt=\"Transparentes\">\n                                        <div class=\"imagenSubfamiliaMenu\">\n                                                                                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_edtrhw_volteada-logo.jpg\"\n                                                    alt=\"Imagen de Transparentes\">\n                                                                                    <\/div>\n                                                                                    Transparentes                                                                            <\/a>\n                                <\/li>\n                                                            <li id=\"menu-familia-1\" class=\"daterium-brand-menu-subitem\">\n\n                                    <a href=\"#mf1sf1\"\n                                        alt=\"Alta visibilidad\">\n                                        <div class=\"imagenSubfamiliaMenu\">\n                                                                                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_spark-yellow lens_volteada-logo.jpg\"\n                                                    alt=\"Imagen de Alta visibilidad\">\n                                                                                    <\/div>\n                                                                                    Alta visibilidad                                                                            <\/a>\n                                <\/li>\n                                                            <li id=\"menu-familia-2\" class=\"daterium-brand-menu-subitem\">\n\n                                    <a href=\"#mf1sf2\"\n                                        alt=\"Oscuras\">\n                                        <div class=\"imagenSubfamiliaMenu\">\n                                                                                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_edmirhw_volteada-logo.jpg\"\n                                                    alt=\"Imagen de Oscuras\">\n                                                                                    <\/div>\n                                                                                    Oscuras                                                                            <\/a>\n                                <\/li>\n                                                            <li id=\"menu-familia-3\" class=\"daterium-brand-menu-subitem\">\n\n                                    <a href=\"#mf1sf3\"\n                                        alt=\"Polarizadas\">\n                                        <div class=\"imagenSubfamiliaMenu\">\n                                                                                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_edpolhw_volteada-logo.jpg\"\n                                                    alt=\"Imagen de Polarizadas\">\n                                                                                    <\/div>\n                                                                                    Polarizadas                                                                            <\/a>\n                                <\/li>\n                                                            <li id=\"menu-familia-4\" class=\"daterium-brand-menu-subitem\">\n\n                                    <a href=\"#mf1sf4\"\n                                        alt=\"Soldadura\">\n                                        <div class=\"imagenSubfamiliaMenu\">\n                                                                                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_spark-ir green_volteada-logo.jpg\"\n                                                    alt=\"Imagen de Soldadura\">\n                                                                                    <\/div>\n                                                                                    Soldadura                                                                            <\/a>\n                                <\/li>\n                                                            <li id=\"menu-familia-5\" class=\"daterium-brand-menu-subitem\">\n\n                                    <a href=\"#mf1sf5\"\n                                        alt=\"Estuches\">\n                                        <div class=\"imagenSubfamiliaMenu\">\n                                                                                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_ru4sg.jpg\"\n                                                    alt=\"Imagen de Estuches\">\n                                                                                    <\/div>\n                                                                                    Estuches                                                                            <\/a>\n                                <\/li>\n                            \n                        <\/ul>\n                    <\/div>\n\n                                    <div class=\"daterium-subfamilia-list-container\">\n                        <ul class=\"daterium-subfamilia-list\" id=\"smf2\">\n\n                                                            <li id=\"menu-familia-0\" class=\"daterium-brand-menu-subitem\">\n\n                                    <a href=\"#mf2sf0\"\n                                        alt=\"Gafas de protecci\u00f3n graduadas\">\n                                        <div class=\"imagenSubfamiliaMenu\">\n                                                                                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_tracer_01.jpg\"\n                                                    alt=\"Imagen de Gafas de protecci\u00f3n graduadas\">\n                                                                                    <\/div>\n                                                                                    Gafas de protecci\u00f3n graduadas                                                                            <\/a>\n                                <\/li>\n                            \n                        <\/ul>\n                    <\/div>\n\n                                    <div class=\"daterium-subfamilia-list-container\">\n                        <ul class=\"daterium-subfamilia-list\" id=\"smf3\">\n\n                                                            <li id=\"menu-familia-0\" class=\"daterium-brand-menu-subitem\">\n\n                                    <a href=\"#mf3sf0\"\n                                        alt=\"WAVE\">\n                                        <div class=\"imagenSubfamiliaMenu\">\n                                                                                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_wave_wasunsu_02.jpg\"\n                                                    alt=\"Imagen de WAVE\">\n                                                                                    <\/div>\n                                                                                    WAVE                                                                            <\/a>\n                                <\/li>\n                                                            <li id=\"menu-familia-1\" class=\"daterium-brand-menu-subitem\">\n\n                                    <a href=\"#mf3sf1\"\n                                        alt=\"STORM\">\n                                        <div class=\"imagenSubfamiliaMenu\">\n                                                                                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_storm_stbgsu.jpg\"\n                                                    alt=\"Imagen de STORM\">\n                                                                                    <\/div>\n                                                                                    STORM                                                                            <\/a>\n                                <\/li>\n                            \n                        <\/ul>\n                    <\/div>\n\n                                    <div class=\"daterium-subfamilia-list-container\">\n                        <ul class=\"daterium-subfamilia-list\" id=\"smf4\">\n\n                                                            <li id=\"menu-familia-0\" class=\"daterium-brand-menu-subitem\">\n\n                                    <a href=\"#mf4sf0\"\n                                        alt=\"Accesorios gafas\">\n                                        <div class=\"imagenSubfamiliaMenu\">\n                                                                                            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_cuassg.jpg\"\n                                                    alt=\"Imagen de Accesorios gafas\">\n                                                                                    <\/div>\n                                                                                    Accesorios gafas                                                                            <\/a>\n                                <\/li>\n                            \n                        <\/ul>\n                    <\/div>\n\n                            <\/div>\n            <div class=\"daterium-brand\">\n                                    <div class=\"daterium-brand-family\" data-menu-text=\"Gafas de protecci\u00f3n\"\n                        id=\"mf1\">\n                        <h2 class=\"daterium-brand-title\">Gafas de protecci\u00f3n<\/h2>\n                        \n                            <div class=\"daterium-brand-subfamily\"\n                                id=\"mf1sf0\">\n                                <div class=\"daterium-brand-toggle\"\n                                    subfamily-id=\"mf1sf0\">\n                                    <div class=\"daterium-brand-subtitle-box\">\n                                        <h4 class=\"daterium-brand-subtitle\">Transparentes<\/h4>\n                                    <\/div>\n                                <\/div>\n                                <div class=\"daterium-lista-categorias-container\">\n                                    <div class=\"daterium-lista-categorias daterium-lista-marcas\">\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1652169\/gafas-de-proteccion-transparentes-epi-ii-edge\" title=\"Gafas de protecci\u00f3n transparentes EPI II EDGE\"\n                                                class=\"daterium-categoria\" id=\"1652169\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_edtrhw_volteada-logo.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n transparentes EPI II EDGE\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n transparentes EPI II EDGE                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1652165\/gafas-de-proteccion-transparentes-certificadas-kn-epi-ii-spark\" title=\"Gafas de protecci\u00f3n transparentes certificadas K\/N EPI II SPARK\"\n                                                class=\"daterium-categoria\" id=\"1652165\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_spark- clear lens_volteada-logo.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n transparentes certificadas K\/N EPI II SPARK\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n transparentes certificadas K\/N EPI II SPARK                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019700\/gafas-de-proteccion-transparentes-con-banda-elastica-epi-ii-orso\" title=\"Gafas de protecci\u00f3n transparentes con banda el\u00e1stica EPI II ORSO\"\n                                                class=\"daterium-categoria\" id=\"1019700\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_orso_orsotrey_01 - copia.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n transparentes con banda el\u00e1stica EPI II ORSO\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n transparentes con banda el\u00e1stica EPI II ORSO                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1406899\/gafas-de-proteccion-transparentes-epi-ii-warrior\" title=\"Gafas de protecci\u00f3n transparentes EPI II WARRIOR\"\n                                                class=\"daterium-categoria\" id=\"1406899\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_warrior_azul.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n transparentes EPI II WARRIOR\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n transparentes EPI II WARRIOR                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1226260\/gafas-de-proteccion-transparentes-de-patillas-grises-epi-ii-evo\" title=\"Gafas de protecci\u00f3n transparentes de patillas grises EPI II EVO\"\n                                                class=\"daterium-categoria\" id=\"1226260\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/evotgr.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n transparentes de patillas grises EPI II EVO\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n transparentes de patillas grises EPI II EVO                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1226262\/gafas-de-proteccion-transparentes-de-patillas-verdes-epi-ii-evo\" title=\"Gafas de protecci\u00f3n transparentes de patillas verdes EPI II EVO\"\n                                                class=\"daterium-categoria\" id=\"1226262\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/evotg.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n transparentes de patillas verdes EPI II EVO\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n transparentes de patillas verdes EPI II EVO                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1226261\/gafas-de-proteccion-transparentes-de-patillas-naranjas-epi-ii-evo\" title=\"Gafas de protecci\u00f3n transparentes de patillas naranjas EPI II EVO\"\n                                                class=\"daterium-categoria\" id=\"1226261\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/evoto.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n transparentes de patillas naranjas EPI II EVO\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n transparentes de patillas naranjas EPI II EVO                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018611\/gafas-de-proteccion-transparentes-intercambiables-epi-ii-runner\" title=\"Gafas de protecci\u00f3n transparentes intercambiables EPI II RUNNER\"\n                                                class=\"daterium-categoria\" id=\"1018611\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_rutrsg_volteada.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n transparentes intercambiables EPI II RUNNER\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n transparentes intercambiables EPI II RUNNER                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1153666\/gafas-de-proteccion-transparentes-no-correctivas-epi-ii-tracer\" title=\"Gafas de protecci\u00f3n transparentes no correctivas EPI II TRACER\"\n                                                class=\"daterium-categoria\" id=\"1153666\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_tracer_01.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n transparentes no correctivas EPI II TRACER\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n transparentes no correctivas EPI II TRACER                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018620\/gafas-de-proteccion-transparentes-epi-ii-eco\" title=\"Gafas de protecci\u00f3n transparentes EPI II ECO\"\n                                                class=\"daterium-categoria\" id=\"1018620\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_ectrsg_volteada.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n transparentes EPI II ECO\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n transparentes EPI II ECO                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018619\/gafas-de-proteccion-transparentes-envolventes-epi-ii-scudo\" title=\"Gafas de protecci\u00f3n transparentes envolventes EPI II SCUDO\"\n                                                class=\"daterium-categoria\" id=\"1018619\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_sctrsg - volteada.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n transparentes envolventes EPI II SCUDO\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n transparentes envolventes EPI II SCUDO                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018618\/gafas-de-proteccion-transparentes-epi-ii-double\" title=\"Gafas de protecci\u00f3n transparentes EPI II DOUBLE\"\n                                                class=\"daterium-categoria\" id=\"1018618\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_dotrsg volteada.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n transparentes EPI II DOUBLE\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n transparentes EPI II DOUBLE                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018621\/guardian-gafas-de-seguridad-panoramicas-transparentes\" title=\"GUARDIAN Gafas de seguridad panor\u00e1micas transparentes\"\n                                                class=\"daterium-categoria\" id=\"1018621\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_gutrsg_volteada.jpg\"\n                                                            alt=\"GUARDIAN Gafas de seguridad panor\u00e1micas transparentes\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            GUARDIAN Gafas de seguridad panor\u00e1micas transparentes                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019028\/indro-gafas-de-seguridad-transparentes\" title=\"INDRO Gafas de seguridad transparentes\"\n                                                class=\"daterium-categoria\" id=\"1019028\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_indro_indrotraw_01.jpg\"\n                                                            alt=\"INDRO Gafas de seguridad transparentes\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            INDRO Gafas de seguridad transparentes                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019032\/folco-gafas-de-seguridad-transparentes\" title=\"FOLCO Gafas de seguridad transparentes\"\n                                                class=\"daterium-categoria\" id=\"1019032\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_folco_folcotrey_01.jpg\"\n                                                            alt=\"FOLCO Gafas de seguridad transparentes\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            FOLCO Gafas de seguridad transparentes                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018605\/eagle-gafas-de-seguridad-transparentes\" title=\"EAGLE Gafas de seguridad transparentes\"\n                                                class=\"daterium-categoria\" id=\"1018605\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_eatrey.jpg\"\n                                                            alt=\"EAGLE Gafas de seguridad transparentes\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            EAGLE Gafas de seguridad transparentes                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018861\/flash-gafas-de-seguridad-transparentes\" title=\"FLASH Gafas de seguridad transparentes\"\n                                                class=\"daterium-categoria\" id=\"1018861\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_fltrhw.jpg\"\n                                                            alt=\"FLASH Gafas de seguridad transparentes\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            FLASH Gafas de seguridad transparentes                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019540\/eco-luxe-gafas-de-seguridad-transparentes\" title=\"ECO LUXE Gafas de seguridad transparentes\"\n                                                class=\"daterium-categoria\" id=\"1019540\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_eltrsg_01.jpg\"\n                                                            alt=\"ECO LUXE Gafas de seguridad transparentes\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            ECO LUXE Gafas de seguridad transparentes                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                            <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                            <div class=\"daterium-brand-subfamily\"\n                                id=\"mf1sf1\">\n                                <div class=\"daterium-brand-toggle\"\n                                    subfamily-id=\"mf1sf1\">\n                                    <div class=\"daterium-brand-subtitle-box\">\n                                        <h4 class=\"daterium-brand-subtitle\">Alta visibilidad<\/h4>\n                                    <\/div>\n                                <\/div>\n                                <div class=\"daterium-lista-categorias-container\">\n                                    <div class=\"daterium-lista-categorias daterium-lista-marcas\">\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1652166\/gafas-de-proteccion-con-lente-amarilla-certificada-kn-epi-ii-spark\" title=\"Gafas de protecci\u00f3n con lente amarilla certificada K\/N EPI II SPARK\"\n                                                class=\"daterium-categoria\" id=\"1652166\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_spark-yellow lens_volteada-logo.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n con lente amarilla certificada K\/N EPI II SPARK\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n con lente amarilla certificada K\/N EPI II SPARK                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019701\/gafas-de-proteccion-con-lente-amarilla-y-banda-elastica-epi-ii-orso\" title=\"Gafas de protecci\u00f3n con lente amarilla y banda el\u00e1stica EPI II ORSO\"\n                                                class=\"daterium-categoria\" id=\"1019701\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_orso_orsoyey_01 - copia.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n con lente amarilla y banda el\u00e1stica EPI II ORSO\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n con lente amarilla y banda el\u00e1stica EPI II ORSO                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1226264\/gafas-de-proteccion-con-lente-amarilla-para-baja-visibilidad-epi-ii-evo\" title=\"Gafas de protecci\u00f3n con lente amarilla para baja visibilidad EPI II EVO\"\n                                                class=\"daterium-categoria\" id=\"1226264\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/evoygr.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n con lente amarilla para baja visibilidad EPI II EVO\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n con lente amarilla para baja visibilidad EPI II EVO                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018612\/gafas-de-proteccion-con-lente-amarilla-intercambiable-epi-ii-runner\" title=\"Gafas de protecci\u00f3n con lente amarilla intercambiable EPI II RUNNER\"\n                                                class=\"daterium-categoria\" id=\"1018612\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_ruysg_volteada.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n con lente amarilla intercambiable EPI II RUNNER\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n con lente amarilla intercambiable EPI II RUNNER                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019029\/indro-gafas-de-seguridad-alta-visibilidad\" title=\"INDRO Gafas de seguridad alta visibilidad\"\n                                                class=\"daterium-categoria\" id=\"1019029\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_indro_indroyaw_01.jpg\"\n                                                            alt=\"INDRO Gafas de seguridad alta visibilidad\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            INDRO Gafas de seguridad alta visibilidad                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019405\/folco-gafas-de-seguridad-alta-visibilidad\" title=\"FOLCO Gafas de seguridad alta visibilidad\"\n                                                class=\"daterium-categoria\" id=\"1019405\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_folco_folcoyey_01.jpg\"\n                                                            alt=\"FOLCO Gafas de seguridad alta visibilidad\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            FOLCO Gafas de seguridad alta visibilidad                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018606\/eagle-gafas-de-seguridad-alta-visibilidad\" title=\"EAGLE Gafas de seguridad alta visibilidad\"\n                                                class=\"daterium-categoria\" id=\"1018606\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_eayey.jpg\"\n                                                            alt=\"EAGLE Gafas de seguridad alta visibilidad\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            EAGLE Gafas de seguridad alta visibilidad                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018862\/flash-gafas-de-seguridad-alta-visibilidad\" title=\"FLASH Gafas de seguridad alta visibilidad\"\n                                                class=\"daterium-categoria\" id=\"1018862\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_flyhw.jpg\"\n                                                            alt=\"FLASH Gafas de seguridad alta visibilidad\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            FLASH Gafas de seguridad alta visibilidad                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                            <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                            <div class=\"daterium-brand-subfamily\"\n                                id=\"mf1sf2\">\n                                <div class=\"daterium-brand-toggle\"\n                                    subfamily-id=\"mf1sf2\">\n                                    <div class=\"daterium-brand-subtitle-box\">\n                                        <h4 class=\"daterium-brand-subtitle\">Oscuras<\/h4>\n                                    <\/div>\n                                <\/div>\n                                <div class=\"daterium-lista-categorias-container\">\n                                    <div class=\"daterium-lista-categorias daterium-lista-marcas\">\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1652170\/gafas-de-proteccion-solares-espejadas-epi-ii-edge\" title=\"Gafas de protecci\u00f3n solares espejadas EPI II EDGE\"\n                                                class=\"daterium-categoria\" id=\"1652170\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_edmirhw_volteada-logo.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n solares espejadas EPI II EDGE\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n solares espejadas EPI II EDGE                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1652167\/gafas-de-proteccion-solares-certificadas-kn-epi-ii-spark\" title=\"Gafas de protecci\u00f3n solares certificadas K\/N EPI II SPARK\"\n                                                class=\"daterium-categoria\" id=\"1652167\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_spark-grey lens_volteada-logo.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n solares certificadas K\/N EPI II SPARK\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n solares certificadas K\/N EPI II SPARK                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019702\/gafas-de-proteccion-solares-con-banda-elastica-epi-ii-orso\" title=\"Gafas de protecci\u00f3n solares con banda el\u00e1stica EPI II ORSO\"\n                                                class=\"daterium-categoria\" id=\"1019702\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_orso_orsosunaw_01 - copia.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n solares con banda el\u00e1stica EPI II ORSO\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n solares con banda el\u00e1stica EPI II ORSO                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1406898\/gafas-de-proteccion-solares-epi-ii-warrior\" title=\"Gafas de protecci\u00f3n solares EPI II WARRIOR\"\n                                                class=\"daterium-categoria\" id=\"1406898\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_warrior_negro.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n solares EPI II WARRIOR\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n solares EPI II WARRIOR                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1226263\/gafas-de-proteccion-solares-industriales-epi-ii-evo\" title=\"Gafas de protecci\u00f3n solares industriales EPI II EVO\"\n                                                class=\"daterium-categoria\" id=\"1226263\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/evosy.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n solares industriales EPI II EVO\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n solares industriales EPI II EVO                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018614\/gafas-de-proteccion-solares-espejadas-intercambiables-epi-ii-runner\" title=\"Gafas de protecci\u00f3n solares espejadas intercambiables EPI II RUNNER\"\n                                                class=\"daterium-categoria\" id=\"1018614\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_rumirsg_oscurecidas_volteada.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n solares espejadas intercambiables EPI II RUNNER\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n solares espejadas intercambiables EPI II RUNNER                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018613\/gafas-de-proteccion-solares-intercambiables-epi-ii-runner\" title=\"Gafas de protecci\u00f3n solares intercambiables EPI II RUNNER\"\n                                                class=\"daterium-categoria\" id=\"1018613\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_rusunsg_volteada.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n solares intercambiables EPI II RUNNER\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n solares intercambiables EPI II RUNNER                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019036\/gafas-de-proteccion-solares-industriales-epi-ii-eco\" title=\"Gafas de protecci\u00f3n solares industriales EPI II ECO\"\n                                                class=\"daterium-categoria\" id=\"1019036\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_ecsunsg_volteada.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n solares industriales EPI II ECO\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n solares industriales EPI II ECO                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019030\/indro-gafas-de-seguridad-oscuras\" title=\"INDRO Gafas de seguridad oscuras\"\n                                                class=\"daterium-categoria\" id=\"1019030\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_indro_indrosunaw_01.jpg\"\n                                                            alt=\"INDRO Gafas de seguridad oscuras\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            INDRO Gafas de seguridad oscuras                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018607\/eagle-gafas-de-seguridad-espejo\" title=\"EAGLE Gafas de seguridad espejo\"\n                                                class=\"daterium-categoria\" id=\"1018607\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_eamirey.jpg\"\n                                                            alt=\"EAGLE Gafas de seguridad espejo\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            EAGLE Gafas de seguridad espejo                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018863\/flash-gafas-de-seguridad-oscuras\" title=\"FLASH Gafas de seguridad oscuras\"\n                                                class=\"daterium-categoria\" id=\"1018863\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_flsunhw.jpg\"\n                                                            alt=\"FLASH Gafas de seguridad oscuras\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            FLASH Gafas de seguridad oscuras                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019404\/folco-gafas-de-seguridad-oscuras\" title=\"FOLCO Gafas de seguridad oscuras\"\n                                                class=\"daterium-categoria\" id=\"1019404\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_folco_folcomirey_01.jpg\"\n                                                            alt=\"FOLCO Gafas de seguridad oscuras\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            FOLCO Gafas de seguridad oscuras                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                            <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                            <div class=\"daterium-brand-subfamily\"\n                                id=\"mf1sf3\">\n                                <div class=\"daterium-brand-toggle\"\n                                    subfamily-id=\"mf1sf3\">\n                                    <div class=\"daterium-brand-subtitle-box\">\n                                        <h4 class=\"daterium-brand-subtitle\">Polarizadas<\/h4>\n                                    <\/div>\n                                <\/div>\n                                <div class=\"daterium-lista-categorias-container\">\n                                    <div class=\"daterium-lista-categorias daterium-lista-marcas\">\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1652171\/gafas-de-proteccion-solares-polarizadas-epi-ii-edge\" title=\"Gafas de protecci\u00f3n solares polarizadas EPI II EDGE\"\n                                                class=\"daterium-categoria\" id=\"1652171\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_edpolhw_volteada-logo.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n solares polarizadas EPI II EDGE\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n solares polarizadas EPI II EDGE                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019031\/indro-gafas-de-seguridad-polarizadas\" title=\"INDRO Gafas de seguridad polarizadas\"\n                                                class=\"daterium-categoria\" id=\"1019031\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_indro_indrosunaw_01.jpg\"\n                                                            alt=\"INDRO Gafas de seguridad polarizadas\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            INDRO Gafas de seguridad polarizadas                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019033\/folco-gafas-de-seguridad-polarizadas\" title=\"FOLCO Gafas de seguridad polarizadas\"\n                                                class=\"daterium-categoria\" id=\"1019033\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_folco_folcopoley_08.jpg\"\n                                                            alt=\"FOLCO Gafas de seguridad polarizadas\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            FOLCO Gafas de seguridad polarizadas                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018608\/eagle-gafas-de-seguridad-polarizadas\" title=\"EAGLE Gafas de seguridad polarizadas\"\n                                                class=\"daterium-categoria\" id=\"1018608\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_eapoley.jpg\"\n                                                            alt=\"EAGLE Gafas de seguridad polarizadas\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            EAGLE Gafas de seguridad polarizadas                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019019\/eagle-gafas-de-seguridad-polarizadas-marrones-con-montura-marron\" title=\"EAGLE Gafas de seguridad polarizadas marrones con montura marr\u00f3n\"\n                                                class=\"daterium-categoria\" id=\"1019019\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_eagle_eapolbbey.jpg\"\n                                                            alt=\"EAGLE Gafas de seguridad polarizadas marrones con montura marr\u00f3n\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            EAGLE Gafas de seguridad polarizadas marrones con montura marr\u00f3n                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019021\/eagle-gafas-de-seguridad-polarizadas-marrones-con-montura-blanca\" title=\"EAGLE Gafas de seguridad polarizadas marrones con montura blanca\"\n                                                class=\"daterium-categoria\" id=\"1019021\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_eapolbwey.jpg\"\n                                                            alt=\"EAGLE Gafas de seguridad polarizadas marrones con montura blanca\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            EAGLE Gafas de seguridad polarizadas marrones con montura blanca                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                            <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                            <div class=\"daterium-brand-subfamily\"\n                                id=\"mf1sf4\">\n                                <div class=\"daterium-brand-toggle\"\n                                    subfamily-id=\"mf1sf4\">\n                                    <div class=\"daterium-brand-subtitle-box\">\n                                        <h4 class=\"daterium-brand-subtitle\">Soldadura<\/h4>\n                                    <\/div>\n                                <\/div>\n                                <div class=\"daterium-lista-categorias-container\">\n                                    <div class=\"daterium-lista-categorias daterium-lista-marcas\">\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1652168\/gafas-de-proteccion-para-soldadura-e-infrarrojos-epi-ii-spark\" title=\"Gafas de protecci\u00f3n para soldadura e infrarrojos EPI II SPARK\"\n                                                class=\"daterium-categoria\" id=\"1652168\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_spark-ir green_volteada-logo.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n para soldadura e infrarrojos EPI II SPARK\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n para soldadura e infrarrojos EPI II SPARK                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018622\/welding-gafas-de-seguridad-para-soldadura-de-gas\" title=\"WELDING Gafas de seguridad para soldadura de gas\"\n                                                class=\"daterium-categoria\" id=\"1018622\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_fld5hw.jpg\"\n                                                            alt=\"WELDING Gafas de seguridad para soldadura de gas\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            WELDING Gafas de seguridad para soldadura de gas                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                            <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                            <div class=\"daterium-brand-subfamily\"\n                                id=\"mf1sf5\">\n                                <div class=\"daterium-brand-toggle\"\n                                    subfamily-id=\"mf1sf5\">\n                                    <div class=\"daterium-brand-subtitle-box\">\n                                        <h4 class=\"daterium-brand-subtitle\">Estuches<\/h4>\n                                    <\/div>\n                                <\/div>\n                                <div class=\"daterium-lista-categorias-container\">\n                                    <div class=\"daterium-lista-categorias daterium-lista-marcas\">\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1189798\/runner-estuche-de-gafas-de-seguridad-allseasons\" title=\"RUNNER Estuche de gafas de seguridad Allseasons\"\n                                                class=\"daterium-categoria\" id=\"1189798\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_ru4sg.jpg\"\n                                                            alt=\"RUNNER Estuche de gafas de seguridad Allseasons\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            RUNNER Estuche de gafas de seguridad Allseasons                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                            <\/div>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                                    <div class=\"daterium-brand-family\" data-menu-text=\"Gafas de protecci\u00f3n graduadas\"\n                        id=\"mf2\">\n                        <h2 class=\"daterium-brand-title\">Gafas de protecci\u00f3n graduadas<\/h2>\n                        \n                            <div class=\"daterium-brand-subfamily\"\n                                id=\"mf2sf0\">\n                                <div class=\"daterium-brand-toggle\"\n                                    subfamily-id=\"mf2sf0\">\n                                    <div class=\"daterium-brand-subtitle-box\">\n                                        <h4 class=\"daterium-brand-subtitle\">Gafas de protecci\u00f3n graduadas<\/h4>\n                                    <\/div>\n                                <\/div>\n                                <div class=\"daterium-lista-categorias-container\">\n                                    <div class=\"daterium-lista-categorias daterium-lista-marcas\">\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1153665\/gafas-de-proteccion-graduadas-epi-ii-tracer\" title=\"Gafas de protecci\u00f3n graduadas EPI II TRACER\"\n                                                class=\"daterium-categoria\" id=\"1153665\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_tracer_01.jpg\"\n                                                            alt=\"Gafas de protecci\u00f3n graduadas EPI II TRACER\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Gafas de protecci\u00f3n graduadas EPI II TRACER                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018616\/reader-gafas-de-seguridad-graduadas-para-vista-cansada\" title=\"READER Gafas de seguridad graduadas para vista cansada\"\n                                                class=\"daterium-categoria\" id=\"1018616\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_reader.jpg\"\n                                                            alt=\"READER Gafas de seguridad graduadas para vista cansada\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            READER Gafas de seguridad graduadas para vista cansada                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                            <\/div>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                                    <div class=\"daterium-brand-family\" data-menu-text=\"Gafas de sol\"\n                        id=\"mf3\">\n                        <h2 class=\"daterium-brand-title\">Gafas de sol<\/h2>\n                        \n                            <div class=\"daterium-brand-subfamily\"\n                                id=\"mf3sf0\">\n                                <div class=\"daterium-brand-toggle\"\n                                    subfamily-id=\"mf3sf0\">\n                                    <div class=\"daterium-brand-subtitle-box\">\n                                        <h4 class=\"daterium-brand-subtitle\">WAVE<\/h4>\n                                    <\/div>\n                                <\/div>\n                                <div class=\"daterium-lista-categorias-container\">\n                                    <div class=\"daterium-lista-categorias daterium-lista-marcas\">\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019441\/wave-gafas-de-sol-lente-negra\" title=\"WAVE Gafas de sol lente negra\"\n                                                class=\"daterium-categoria\" id=\"1019441\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_wave_wasunsu_02.jpg\"\n                                                            alt=\"WAVE Gafas de sol lente negra\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            WAVE Gafas de sol lente negra                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019442\/wave-gafas-de-sol-lente-espejo-azul\" title=\"WAVE Gafas de sol lente espejo azul\"\n                                                class=\"daterium-categoria\" id=\"1019442\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_wave_wablmsu_02.jpg\"\n                                                            alt=\"WAVE Gafas de sol lente espejo azul\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            WAVE Gafas de sol lente espejo azul                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019443\/wave-gafas-de-sol-lente-espejo-verde\" title=\"WAVE Gafas de sol lente espejo verde\"\n                                                class=\"daterium-categoria\" id=\"1019443\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_wave_wagrmsu_02.jpg\"\n                                                            alt=\"WAVE Gafas de sol lente espejo verde\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            WAVE Gafas de sol lente espejo verde                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019541\/wave-gafas-de-sol-polarizadas\" title=\"WAVE Gafas de sol polarizadas\"\n                                                class=\"daterium-categoria\" id=\"1019541\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_wave_wasunsu_02.jpg\"\n                                                            alt=\"WAVE Gafas de sol polarizadas\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            WAVE Gafas de sol polarizadas                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                            <\/div>\n                                <\/div>\n                            <\/div>\n                        \n                            <div class=\"daterium-brand-subfamily\"\n                                id=\"mf3sf1\">\n                                <div class=\"daterium-brand-toggle\"\n                                    subfamily-id=\"mf3sf1\">\n                                    <div class=\"daterium-brand-subtitle-box\">\n                                        <h4 class=\"daterium-brand-subtitle\">STORM<\/h4>\n                                    <\/div>\n                                <\/div>\n                                <div class=\"daterium-lista-categorias-container\">\n                                    <div class=\"daterium-lista-categorias daterium-lista-marcas\">\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1695893\/storm-gafas-de-sol-categoria-3-uv-a-uv-b-lente-negra-degradada\" title=\"STORM Gafas de sol categor\u00eda 3 UV-A UV-B lente negra degradada\"\n                                                class=\"daterium-categoria\" id=\"1695893\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_storm_stbgsu.jpg\"\n                                                            alt=\"STORM Gafas de sol categor\u00eda 3 UV-A UV-B lente negra degradada\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            STORM Gafas de sol categor\u00eda 3 UV-A UV-B lente negra degradada                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1695894\/storm-gafas-de-sol-categoria-3-uv-a-uv-b-lente-azul\" title=\"STORM Gafas de sol categor\u00eda 3 UV-A UV-B lente azul\"\n                                                class=\"daterium-categoria\" id=\"1695894\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_stblmsu.jpg\"\n                                                            alt=\"STORM Gafas de sol categor\u00eda 3 UV-A UV-B lente azul\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            STORM Gafas de sol categor\u00eda 3 UV-A UV-B lente azul                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1695895\/storm-gafas-de-sol-categoria-3-uv-a-uv-b-lente-espejo-roja\" title=\"STORM Gafas de sol categor\u00eda 3 UV-A UV-B lente espejo roja\"\n                                                class=\"daterium-categoria\" id=\"1695895\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_stredsu.jpg\"\n                                                            alt=\"STORM Gafas de sol categor\u00eda 3 UV-A UV-B lente espejo roja\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            STORM Gafas de sol categor\u00eda 3 UV-A UV-B lente espejo roja                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1695896\/storm-gafas-de-sol-categoria-3-uv-a-uv-b-lente-polarizada\" title=\"STORM Gafas de sol categor\u00eda 3 UV-A UV-B lente polarizada\"\n                                                class=\"daterium-categoria\" id=\"1695896\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_stpolsu.jpg\"\n                                                            alt=\"STORM Gafas de sol categor\u00eda 3 UV-A UV-B lente polarizada\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            STORM Gafas de sol categor\u00eda 3 UV-A UV-B lente polarizada                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                            <\/div>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                                    <div class=\"daterium-brand-family\" data-menu-text=\"Accesorios gafas\"\n                        id=\"mf4\">\n                        <h2 class=\"daterium-brand-title\">Accesorios gafas<\/h2>\n                        \n                            <div class=\"daterium-brand-subfamily\"\n                                id=\"mf4sf0\">\n                                <div class=\"daterium-brand-toggle\"\n                                    subfamily-id=\"mf4sf0\">\n                                    <div class=\"daterium-brand-subtitle-box\">\n                                        <h4 class=\"daterium-brand-subtitle\">Accesorios gafas<\/h4>\n                                    <\/div>\n                                <\/div>\n                                <div class=\"daterium-lista-categorias-container\">\n                                    <div class=\"daterium-lista-categorias daterium-lista-marcas\">\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1018623\/estuche-para-gafas\" title=\"Estuche para gafas\"\n                                                class=\"daterium-categoria\" id=\"1018623\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_cuassg.jpg\"\n                                                            alt=\"Estuche para gafas\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Estuche para gafas                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019439\/funda-de-microfibra\" title=\"Funda de microfibra\"\n                                                class=\"daterium-categoria\" id=\"1019439\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_fdmsg.jpg\"\n                                                            alt=\"Funda de microfibra\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Funda de microfibra                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019440\/cordon-para-gafas\" title=\"Cord\u00f3n para gafas\"\n                                                class=\"daterium-categoria\" id=\"1019440\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_corsg.jpg\"\n                                                            alt=\"Cord\u00f3n para gafas\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Cord\u00f3n para gafas                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1019759\/kit-de-mantenimiento-para-lentes-y-pantallas\" title=\"Kit de mantenimiento para lentes y pantallas\"\n                                                class=\"daterium-categoria\" id=\"1019759\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/eagle_kit_pulizia_foto.jpg\"\n                                                            alt=\"Kit de mantenimiento para lentes y pantallas\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Kit de mantenimiento para lentes y pantallas                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                                    <a href=\"https:\/\/www.eagle-glasses.com\/pt\/productos\/1020206\/spray-antivaho-nanotecnologico-para-lentes-de-gafas\" title=\"Spray antivaho nanotecnol\u00f3gico para lentes de gafas\"\n                                                class=\"daterium-categoria\" id=\"1020206\">\n                                                <div class=\"daterium-list-inner\">\n                                                    <div class=\"imagenEfecto\">\n                                                        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.dateriumsystem.com\/appfiles\/clientes\/3\/catalogo\/500x500\/exeaav-210101_expo_antivaho.jpg\"\n                                                            alt=\"Spray antivaho nanotecnol\u00f3gico para lentes de gafas\" \/>\n                                                    <\/div>\n\n                                                    <div class=\"daterium-list-title-container\">\n                                                        <h5 class=\"daterium-list-title\">\n                                                            Spray antivaho nanotecnol\u00f3gico para lentes de gafas                                                        <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/a>\n                                                                            <\/div>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                            <\/div>\n\n        <\/div>\n    <\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-page.php","meta":{"footnotes":""},"class_list":["post-11","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.eagle-glasses.com\/pt\/wp-json\/wp\/v2\/pages\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eagle-glasses.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.eagle-glasses.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.eagle-glasses.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eagle-glasses.com\/pt\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":2,"href":"https:\/\/www.eagle-glasses.com\/pt\/wp-json\/wp\/v2\/pages\/11\/revisions"}],"predecessor-version":[{"id":507,"href":"https:\/\/www.eagle-glasses.com\/pt\/wp-json\/wp\/v2\/pages\/11\/revisions\/507"}],"wp:attachment":[{"href":"https:\/\/www.eagle-glasses.com\/pt\/wp-json\/wp\/v2\/media?parent=11"}],"curies":[{"name":"palavra-passe","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}